{"id":101581,"date":"2020-11-03T11:07:18","date_gmt":"2020-11-03T11:07:18","guid":{"rendered":"https:\/\/fabrizifamily.com\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/"},"modified":"2020-11-03T11:07:18","modified_gmt":"2020-11-03T11:07:18","slug":"il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci","status":"publish","type":"post","link":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/","title":{"rendered":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina"},"content":{"rendered":"<p><em>Idee per ricette dolci e salate, arricchite dal sapore di un ingrediente versatile, originale e simbolo della tradizione: le visciole sciroppate. Ecco qualche idea per utilizzarle in cucina!<\/em><!--more--><\/p>\n<p>Della stessa famiglia delle ciliegie e delle amarene <a href=\"https:\/\/fabrizifamily.com\/visciole-amarene-differenza\/\">(ma diverse da entrambe!)<\/a>, le visciole rappresentano uno dei pi\u00f9 importanti patrimoni gastronomici delle Marche. Una <a href=\"https:\/\/fabrizifamily.com\/visciole-al-sole\/\">produzione legata a doppio filo con la tradizione locale<\/a>, sopravvissuta a secoli di storia agroalimentare della regione.<\/p>\n<p>La coltivazione delle visciole, infatti, \u00e8 nota nelle Marche sin dal tempo dei romani, che le utilizzavano per correggere il vino dell&#8217;epoca, notoriamente disarmonico a causa delle primitive tecnologie di produzione. Un&#8217;abitudine affinata nei secoli successivi con la produzione del <a href=\"https:\/\/fabrizifamily.com\/vino-e-visciole-patrimonio-marchigiano\/\">vino di visciole<\/a>, dal bouquet aromatico e corposo, ideale a fine pasto per accompagnare frutta e dessert.\u00a0 \u00a0Nella cucina marchigiana, inoltre, le visciole sono da sempre utilizzate per <a href=\"https:\/\/fabrizifamily.com\/?post_type=product&#038;p=326\">la produzione di confetture<\/a> e delle tradizionali <a href=\"https:\/\/fabrizifamily.com\/prodotto\/dame-visciola-sciroppate\/\">\u201cdame di visciole\u201d<\/a> o \u201cvisciole sciroppate\u201d.<\/p>\n<p>Una ricetta semplice a base di pochissimi ingredienti: visciole, zucchero e&#8230; tanta pazienza! Ed \u00e8 in questo modo che, ancora oggi, noi di Fabrizi Family prepariamo le nostre <a href=\"https:\/\/fabrizifamily.com\/prodotto\/dame-visciola-sciroppate\/\">dame di visciole<\/a>, perfette per farcire torte, muffin, <a href=\"https:\/\/fabrizifamily.com\/maritozzi-marchigiani-con-confettura\/\">cornetti e maritozzi<\/a>, ma ideali anche per ricette a base di carne.<\/p>\n<h2>Ricette dolci con visciole sciroppate<\/h2>\n<div class=\"cta-container\">\n<div class=\"cta-column-2\">\n<h3>STUPISCI CON LA CORTE DI VISCIOLA<\/h3>\n<p>Fabrizi Family seleziona per te i migliori prodotti della natura: mieli, marmellate e confetture della tradizione da produttori certificati.<\/p>\n<p><a class=\"cta-button\" href=\"https:\/\/fabrizifamily.com\/prodotto\/corte-visciola-box\/\">GUARDA L&#8217;OFFERTA<\/a><\/p>\n<\/div>\n<p><!-- set cta-column-1 height according to the amount of text --><\/p>\n<div class=\"cta-column-1\"><img decoding=\"async\" src=\"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2018\/11\/CV2.png\" \/><\/div>\n<div class=\"cta-clearfix\"><\/div>\n<\/div>\n<p>Morbide, succose e assolutamente inimitabili: le visciole sciroppate rappresentano un ingrediente versatile e originale per arricchire dolci di ogni tipo.<\/p>\n<p>Dal liquido, ottenuto mediante la sola infusione del frutto nello zucchero, si ricava uno sciroppo perfetto per accompagnare yogurt, budini, panna cotta con effetto scenico assicurato. La bacca di color rosso rubino, morbida e dal sapore vagamente agrodolce, \u00e8 una guarnitura elegante e originale per muffin, tortini, semifreddi, cheesecake e torte di panna e frutta.<\/p>\n<p>Non c&#8217;\u00e8 limite alla fantasia! Grazie al loro carattere dolce ma, allo stesso tempo, delicato, le visciole sciroppate si prestano a innumerevoli creazioni di pasticceria, sempre in grado di stupire e accattivare. Puoi provarle nei brownies al cioccolato, o \u201cnasconderle\u201d all&#8217;interno di muffin dolci allo yogurt, per un effetto sorpresa davvero delizioso.<\/p>\n<p>Usale per arricchire torte bavaresi, crema di latte o per guarnire la deliziosa torta foresta nera al cioccolato. Le visciole sciroppate sono, inoltre, ideali per dessert vegani, come semifreddi al latte di riso, pudding di chia, avena o soia, o budini di semolino alla frutta!<\/p>\n<h2>Ricette di carne con visciole sciroppate<\/h2>\n<p>Non solo dessert, ma anche secondi piatti e contorni. La cucina tipica marchigiana \u00e8 ricca di ricette che attingono direttamente dalla tradizione medievale. Dal maiale in salsa di <a href=\"https:\/\/fabrizifamily.com\/mele-rosa-dei-monti-sibillin-storia\/\">mele rosa dei monti Sibillini<\/a> fino al caratteristico coniglio in porchetta marchigiano: quello tra carne e frutta rappresenta un binomio tutto da riscoprire.<\/p>\n<p>In questo, le visciole sciroppate rappresentano un ingrediente facile da utilizzare, creativo e di grande effetto. Perfetto per carni rosse, come maiale e manzo, ma anche per quelle bianche.<\/p>\n<p>Puoi aggiungere visciole sciroppate al ripieno di castagne per farcire il tacchino, o utilizzarle per preparare una deliziosa salsa per accompagnare petto d&#8217;anatra, roastbeef, bistecche e tagliate di manzo. Lo sciroppo di visciole \u00e8 ideale per dare un \u201ctocco in pi\u00f9\u201d a vitello, agnello, polpettone, spezzatino e filetto di maiale, con le bacche a guarnizione del vassoio da portata, per conquistare i tuoi ospiti.<\/p>\n<h3>Ecco una ricetta veloce per un filetto di maiale alle visciole davvero eccezionale:<\/h3>\n<p>Ingredienti e dosi per 4 persone.<\/p>\n<ul>\n<li>300g di filetto di maiale;<\/li>\n<li>mezzo bicchiere di vino di visciole;<\/li>\n<li>15 dame di visciole con sciroppo;<\/li>\n<li>50ml di acqua;<\/li>\n<li>Salvia, Rosmarino, Timo, Aglio, sale aromatizzato;<\/li>\n<li>Olio EVO<\/li>\n<\/ul>\n<p>Calcola bene il tempo di cottura del filetto in base al tipo di condimento che scegli di abbinarvi (crema di patate, crema di piselli, verdure, etc).<\/p>\n<p>Monda il filetto da grasso e tessuto in eccesso, ricavandone quattro grossi pezzi da 5 cm ciascuno circa. Riponi in ogni singolo pezzo foglie o rametti di salva, rosmarino e timo e una o due visciole, in base alla grandezza del taglio di carne, e lega il tutto con spago da cucina.<\/p>\n<p>In una casseruola fai soffriggere aglio in camicia e erbe, riponendo successivamente i filetti di carne legati e distanziati tra loro. Non appena la carne avr\u00e0 preso un colore pi\u00f9 bruno, voltala per cuocerla uniformemente anche sul lato opposto. Lascia cuocere qualche minuto per lato, girando le carne con delle pinze, invece che con una forchetta, per evitare di bucarla.<\/p>\n<p>Una volta insaporita e dorata, sfuma il tutto con vino di visciole e continua la cottura con coperchio per 5 minuti. Rimuovi l&#8217;aglio e le erbe aromatiche e versa nella casseruola acqua e sciroppo di amarene e lascia cuocere per 8 minuti circa. Sistema i filetti sul piatto distribuendo uno strato di condimento sotto di essi, e le visciole a guarnizione. Utilizza il sugo di cottura per insaporire la carne e il filetto \u00e8 servito!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Idee per ricette dolci e salate, arricchite dal sapore di un ingrediente versatile, originale e simbolo della tradizione: le visciole sciroppate. Ecco qualche idea per utilizzarle in cucina!<\/p>\n","protected":false},"author":37,"featured_media":101582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[180],"tags":[],"class_list":["post-101581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prodotti-tipici-marchigiani-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family\" \/>\n<meta property=\"og:description\" content=\"Idee per ricette dolci e salate, arricchite dal sapore di un ingrediente versatile, originale e simbolo della tradizione: le visciole sciroppate. Ecco qualche idea per utilizzarle in cucina!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/\" \/>\n<meta property=\"og:site_name\" content=\"Fabrizi Family\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T11:07:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2018\/11\/CV2.png\" \/>\n<meta name=\"author\" content=\"Giordano Chiodi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giordano Chiodi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/\"},\"author\":{\"name\":\"Giordano Chiodi\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/#\\\/schema\\\/person\\\/604bdd05346f68a93a4e78d2de43ff6c\"},\"headline\":\"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina\",\"datePublished\":\"2020-11-03T11:07:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/\"},\"wordCount\":818,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fabrizifamily.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/filetto-visciole.jpg\",\"articleSection\":[\"Typical Marche products\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/\",\"url\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/\",\"name\":\"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fabrizifamily.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/filetto-visciole.jpg\",\"datePublished\":\"2020-11-03T11:07:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/#\\\/schema\\\/person\\\/604bdd05346f68a93a4e78d2de43ff6c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fabrizifamily.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/filetto-visciole.jpg\",\"contentUrl\":\"https:\\\/\\\/fabrizifamily.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/filetto-visciole.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/\",\"name\":\"Fabrizi Family\",\"description\":\"Beverage, Food e Sweeties dalle Marche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/#\\\/schema\\\/person\\\/604bdd05346f68a93a4e78d2de43ff6c\",\"name\":\"Giordano Chiodi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g\",\"caption\":\"Giordano Chiodi\"},\"url\":\"https:\\\/\\\/fabrizifamily.com\\\/en\\\/author\\\/g-chiodiwebjesi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/","og_locale":"en_US","og_type":"article","og_title":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family","og_description":"Idee per ricette dolci e salate, arricchite dal sapore di un ingrediente versatile, originale e simbolo della tradizione: le visciole sciroppate. Ecco qualche idea per utilizzarle in cucina!","og_url":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/","og_site_name":"Fabrizi Family","article_published_time":"2020-11-03T11:07:18+00:00","og_image":[{"url":"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2018\/11\/CV2.png","type":"","width":"","height":""}],"author":"Giordano Chiodi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Giordano Chiodi","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#article","isPartOf":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/"},"author":{"name":"Giordano Chiodi","@id":"https:\/\/fabrizifamily.com\/en\/#\/schema\/person\/604bdd05346f68a93a4e78d2de43ff6c"},"headline":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina","datePublished":"2020-11-03T11:07:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/"},"wordCount":818,"commentCount":0,"image":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#primaryimage"},"thumbnailUrl":"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2020\/11\/filetto-visciole.jpg","articleSection":["Typical Marche products"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/","url":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/","name":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina - Fabrizi Family","isPartOf":{"@id":"https:\/\/fabrizifamily.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#primaryimage"},"image":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#primaryimage"},"thumbnailUrl":"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2020\/11\/filetto-visciole.jpg","datePublished":"2020-11-03T11:07:18+00:00","author":{"@id":"https:\/\/fabrizifamily.com\/en\/#\/schema\/person\/604bdd05346f68a93a4e78d2de43ff6c"},"breadcrumb":{"@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#primaryimage","url":"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2020\/11\/filetto-visciole.jpg","contentUrl":"https:\/\/fabrizifamily.com\/wp-content\/uploads\/2020\/11\/filetto-visciole.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/fabrizifamily.com\/en\/il-gusto-esplosivo-delle-visciole-sciroppate-ecco-come-usarle-in-cucina-non-solo-dolci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fabrizifamily.com\/en\/"},{"@type":"ListItem","position":2,"name":"Il gusto esplosivo delle visciole sciroppate, ecco come usarle in cucina"}]},{"@type":"WebSite","@id":"https:\/\/fabrizifamily.com\/en\/#website","url":"https:\/\/fabrizifamily.com\/en\/","name":"Fabrizi Family","description":"Beverage, Food e Sweeties dalle Marche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fabrizifamily.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fabrizifamily.com\/en\/#\/schema\/person\/604bdd05346f68a93a4e78d2de43ff6c","name":"Giordano Chiodi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c46845a654a7070ae8af0f4b4617cd415079874df618cb254f052631dae72b6?s=96&d=mm&r=g","caption":"Giordano Chiodi"},"url":"https:\/\/fabrizifamily.com\/en\/author\/g-chiodiwebjesi-it\/"}]}},"_links":{"self":[{"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/posts\/101581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/comments?post=101581"}],"version-history":[{"count":0,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/posts\/101581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/media\/101582"}],"wp:attachment":[{"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/media?parent=101581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/categories?post=101581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fabrizifamily.com\/en\/wp-json\/wp\/v2\/tags?post=101581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}